{"id":357,"date":"2024-03-07T10:29:20","date_gmt":"2024-03-07T13:29:20","guid":{"rendered":"https:\/\/esportbetnews.com\/?p=357"},"modified":"2024-03-10T08:32:01","modified_gmt":"2024-03-10T11:32:01","slug":"rapidinhas-do-sportbetnews-competicoes","status":"publish","type":"post","link":"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/","title":{"rendered":"Rapidinhas do Sportbetnews: Competi\u00e7\u00f5es"},"content":{"rendered":"\n<p><strong>Campeonato Paulista:<\/strong><\/p>\n\n\n\n<p>O campeonato paulista vive seu momento de defini\u00e7\u00e3o. Com exce\u00e7\u00e3o do grupo D onde S\u00e3o Paulo, Novorinzontino e S\u00e3o Bernardo disputam duas vagas para a pr\u00f3xima fase.<\/p>\n\n\n\n<p>A grande surpresa e ao mesmo tempo vexame foi no grupo C. O Corinthians, que sempre \u00e9 um dos favoritos a ganhar a competi\u00e7\u00e3o, n\u00e3o conseguiu se classificar para a pr\u00f3xima fase e pior, lutou nas \u00faltimas rodadas para n\u00e3o cair para a s\u00e9rie A-2 (s\u00e9rie B do Paulista).<\/p>\n\n\n\n<p><strong>Campeonato Carioca:<\/strong><\/p>\n\n\n\n<p>O Carioc\u00e3o deste ano est\u00e1 marcado pela n\u00e3o classifica\u00e7\u00e3o do Botafogo para as semi-finais da competi\u00e7\u00e3o. O Alvinegro terminou a Ta\u00e7a Guanabara na 5\u00aa coloca\u00e7\u00e3o.<\/p>\n\n\n\n<p>A equipe ter\u00e1 que disputar a Ta\u00e7a Rio,  entre os 5\u00ba e 8\u00ba colocados da primeira fase do torneio. O campe\u00e3o garante vaga na Copa do Brasil de 2025, por causa do novo regulamento da CBF.<\/p>\n\n\n\n<p><strong>Liga dos Campe\u00f5es:<\/strong><\/p>\n\n\n\n<p>A Champions League est\u00e1 apresentando as principais equipes que buscam o t\u00edtulo da maior competi\u00e7\u00e3o de clubes do mundo. A champions est\u00e1 na fase de Oitavas de finais e na pr\u00f3xima semana (ter\u00e7a dia 12 e quarta dia 13) ser\u00e3o definidos os \u00faltimo clubes que ir\u00e3o para as quarta de finais. Bayern de Munique, Real Madrid e Manchester City s\u00e3o os quatro primeiros times com classifica\u00e7\u00e3o confirmada para a pr\u00f3xima fase da competi\u00e7\u00e3o.<\/p>\n\n\n\n<p>Quartas de finais:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jogos de ida: 9 e 10 de abril<\/li>\n\n\n\n<li>Jogos de volta: 16 e 17 de abril<\/li>\n<\/ul>\n\n\n\n<p>Sorteios:<\/p>\n\n\n\n<p>O sorteio das quartas de final da Champions est\u00e1 marcado para o dia 15 de mar\u00e7o, quando todos os classificados forem conhecidos.<\/p>\n\n\n\n<p>J\u00e1 a grande final da Champions, est\u00e1 marcada para o dia 1\u00ba de junho. O palco da decis\u00e3o ser\u00e1 o est\u00e1dio de Wembley, em Londres.<\/p>\n\n\n\n<p><strong>Brasileir\u00e3o:<\/strong><\/p>\n\n\n\n<p>Ap\u00f3s recusar os pedidos dos clubes para a paralisa\u00e7\u00e3o do torneio durante a Copa Am\u00e9rica, a CBF detalhou a tabela da competi\u00e7\u00e3o com as 38 rodadas, iniciando nos dias 13, 14 e 15 de abril, fazendo com que clubes que ter\u00e3o jogadores convocados por suas sele\u00e7\u00f5es, tenham grandes desfalques nos campeonato nacionais. Absurdo!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Campeonato Paulista: O campeonato paulista vive seu momento de defini\u00e7\u00e3o. Com exce\u00e7\u00e3o do grupo D onde S\u00e3o Paulo, Novorinzontino e S\u00e3o Bernardo disputam duas vagas para a pr\u00f3xima fase. A grande surpresa e ao mesmo tempo vexame foi no grupo C. O Corinthians, que sempre \u00e9 um dos favoritos a ganhar a competi\u00e7\u00e3o, n\u00e3o conseguiu [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[3,41,37],"tags":[99,52,98,56],"class_list":{"0":"post-357","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-futebol","8":"category-futebol_internacional","9":"category-futebol_regional","10":"tag-brasileirao","11":"tag-cariocao","12":"tag-champions-league","13":"tag-paulistao"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rapidinhas do Sportbetnews: Competi\u00e7\u00f5es - Esport Bet News<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rapidinhas do Sportbetnews: Competi\u00e7\u00f5es - Esport Bet News\" \/>\n<meta property=\"og:description\" content=\"Campeonato Paulista: O campeonato paulista vive seu momento de defini\u00e7\u00e3o. Com exce\u00e7\u00e3o do grupo D onde S\u00e3o Paulo, Novorinzontino e S\u00e3o Bernardo disputam duas vagas para a pr\u00f3xima fase. A grande surpresa e ao mesmo tempo vexame foi no grupo C. O Corinthians, que sempre \u00e9 um dos favoritos a ganhar a competi\u00e7\u00e3o, n\u00e3o conseguiu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/\" \/>\n<meta property=\"og:site_name\" content=\"Esport Bet News\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-07T13:29:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-10T11:32:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/esportbetnews.com\/wp-content\/uploads\/2023\/12\/cropped-Untitled-111.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jo\u00e3o Paulo Bastos\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jo\u00e3o Paulo Bastos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/\"},\"author\":{\"name\":\"Jo\u00e3o Paulo Bastos\",\"@id\":\"https:\/\/esportbetnews.com\/#\/schema\/person\/f1d08ff6386c9ee7b8533d2b175248fa\"},\"headline\":\"Rapidinhas do Sportbetnews: Competi\u00e7\u00f5es\",\"datePublished\":\"2024-03-07T13:29:20+00:00\",\"dateModified\":\"2024-03-10T11:32:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/\"},\"wordCount\":366,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/esportbetnews.com\/#organization\"},\"keywords\":[\"brasileir\u00e3o\",\"carioc\u00e3o\",\"champions league\",\"Paulist\u00e3o\"],\"articleSection\":[\"Futebol\",\"Internacional\",\"Regional\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/\",\"url\":\"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/\",\"name\":\"Rapidinhas do Sportbetnews: Competi\u00e7\u00f5es - Esport Bet News\",\"isPartOf\":{\"@id\":\"https:\/\/esportbetnews.com\/#website\"},\"datePublished\":\"2024-03-07T13:29:20+00:00\",\"dateModified\":\"2024-03-10T11:32:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/esportbetnews.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rapidinhas do Sportbetnews: Competi\u00e7\u00f5es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/esportbetnews.com\/#website\",\"url\":\"https:\/\/esportbetnews.com\/\",\"name\":\"Esport Bet News\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/esportbetnews.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/esportbetnews.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/esportbetnews.com\/#organization\",\"name\":\"Esport Bet News\",\"url\":\"https:\/\/esportbetnews.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/esportbetnews.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/esportbetnews.com\/wp-content\/uploads\/2023\/12\/Untitled-1.png\",\"contentUrl\":\"https:\/\/esportbetnews.com\/wp-content\/uploads\/2023\/12\/Untitled-1.png\",\"width\":512,\"height\":512,\"caption\":\"Esport Bet News\"},\"image\":{\"@id\":\"https:\/\/esportbetnews.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/esportbetnews.com\/#\/schema\/person\/f1d08ff6386c9ee7b8533d2b175248fa\",\"name\":\"Jo\u00e3o Paulo Bastos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/esportbetnews.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/esportbetnews.com\/wp-content\/uploads\/2023\/12\/foto-perfil-joao-paulo.jpg\",\"contentUrl\":\"https:\/\/esportbetnews.com\/wp-content\/uploads\/2023\/12\/foto-perfil-joao-paulo.jpg\",\"caption\":\"Jo\u00e3o Paulo Bastos\"},\"description\":\"Reporter esportivo\",\"url\":\"https:\/\/esportbetnews.com\/index.php\/author\/joaopaulo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rapidinhas do Sportbetnews: Competi\u00e7\u00f5es - Esport Bet News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Rapidinhas do Sportbetnews: Competi\u00e7\u00f5es - Esport Bet News","og_description":"Campeonato Paulista: O campeonato paulista vive seu momento de defini\u00e7\u00e3o. Com exce\u00e7\u00e3o do grupo D onde S\u00e3o Paulo, Novorinzontino e S\u00e3o Bernardo disputam duas vagas para a pr\u00f3xima fase. A grande surpresa e ao mesmo tempo vexame foi no grupo C. O Corinthians, que sempre \u00e9 um dos favoritos a ganhar a competi\u00e7\u00e3o, n\u00e3o conseguiu [&hellip;]","og_url":"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/","og_site_name":"Esport Bet News","article_published_time":"2024-03-07T13:29:20+00:00","article_modified_time":"2024-03-10T11:32:01+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/esportbetnews.com\/wp-content\/uploads\/2023\/12\/cropped-Untitled-111.png","type":"image\/png"}],"author":"Jo\u00e3o Paulo Bastos","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jo\u00e3o Paulo Bastos","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/#article","isPartOf":{"@id":"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/"},"author":{"name":"Jo\u00e3o Paulo Bastos","@id":"https:\/\/esportbetnews.com\/#\/schema\/person\/f1d08ff6386c9ee7b8533d2b175248fa"},"headline":"Rapidinhas do Sportbetnews: Competi\u00e7\u00f5es","datePublished":"2024-03-07T13:29:20+00:00","dateModified":"2024-03-10T11:32:01+00:00","mainEntityOfPage":{"@id":"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/"},"wordCount":366,"commentCount":0,"publisher":{"@id":"https:\/\/esportbetnews.com\/#organization"},"keywords":["brasileir\u00e3o","carioc\u00e3o","champions league","Paulist\u00e3o"],"articleSection":["Futebol","Internacional","Regional"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/","url":"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/","name":"Rapidinhas do Sportbetnews: Competi\u00e7\u00f5es - Esport Bet News","isPartOf":{"@id":"https:\/\/esportbetnews.com\/#website"},"datePublished":"2024-03-07T13:29:20+00:00","dateModified":"2024-03-10T11:32:01+00:00","breadcrumb":{"@id":"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/esportbetnews.com\/index.php\/2024\/03\/07\/rapidinhas-do-sportbetnews-competicoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/esportbetnews.com\/"},{"@type":"ListItem","position":2,"name":"Rapidinhas do Sportbetnews: Competi\u00e7\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/esportbetnews.com\/#website","url":"https:\/\/esportbetnews.com\/","name":"Esport Bet News","description":"","publisher":{"@id":"https:\/\/esportbetnews.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esportbetnews.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/esportbetnews.com\/#organization","name":"Esport Bet News","url":"https:\/\/esportbetnews.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/esportbetnews.com\/#\/schema\/logo\/image\/","url":"https:\/\/esportbetnews.com\/wp-content\/uploads\/2023\/12\/Untitled-1.png","contentUrl":"https:\/\/esportbetnews.com\/wp-content\/uploads\/2023\/12\/Untitled-1.png","width":512,"height":512,"caption":"Esport Bet News"},"image":{"@id":"https:\/\/esportbetnews.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/esportbetnews.com\/#\/schema\/person\/f1d08ff6386c9ee7b8533d2b175248fa","name":"Jo\u00e3o Paulo Bastos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/esportbetnews.com\/#\/schema\/person\/image\/","url":"https:\/\/esportbetnews.com\/wp-content\/uploads\/2023\/12\/foto-perfil-joao-paulo.jpg","contentUrl":"https:\/\/esportbetnews.com\/wp-content\/uploads\/2023\/12\/foto-perfil-joao-paulo.jpg","caption":"Jo\u00e3o Paulo Bastos"},"description":"Reporter esportivo","url":"https:\/\/esportbetnews.com\/index.php\/author\/joaopaulo\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/esportbetnews.com\/wp-content\/uploads\/2023\/12\/cropped-Untitled-111.png","_links":{"self":[{"href":"https:\/\/esportbetnews.com\/index.php\/wp-json\/wp\/v2\/posts\/357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esportbetnews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esportbetnews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esportbetnews.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/esportbetnews.com\/index.php\/wp-json\/wp\/v2\/comments?post=357"}],"version-history":[{"count":4,"href":"https:\/\/esportbetnews.com\/index.php\/wp-json\/wp\/v2\/posts\/357\/revisions"}],"predecessor-version":[{"id":362,"href":"https:\/\/esportbetnews.com\/index.php\/wp-json\/wp\/v2\/posts\/357\/revisions\/362"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esportbetnews.com\/index.php\/wp-json\/wp\/v2\/media\/223"}],"wp:attachment":[{"href":"https:\/\/esportbetnews.com\/index.php\/wp-json\/wp\/v2\/media?parent=357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esportbetnews.com\/index.php\/wp-json\/wp\/v2\/categories?post=357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esportbetnews.com\/index.php\/wp-json\/wp\/v2\/tags?post=357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}